{"id":3247,"date":"2022-03-02T10:10:55","date_gmt":"2022-03-02T09:10:55","guid":{"rendered":"https:\/\/alko-airtechnology.com\/?post_type=wbq_product&#038;p=3247"},"modified":"2025-05-14T14:43:09","modified_gmt":"2025-05-14T12:43:09","slug":"al-ko-easyair-your-central-ventilation-unit","status":"publish","type":"wbq_product","link":"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/","title":{"rendered":"AL-KO EASYAIR\u00ae &#8211; Tw\u00f3j centralny system wentylacji"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[]},"class_list":["post-3247","wbq_product","type-wbq_product","status-publish","hentry"],"acf":[],"yoast_head":"<title>AL-KO EASYAIR\u00ae | AL-KO Air Technology<\/title>\n<meta name=\"description\" content=\"Nasza wydajna kompaktowa jednostka wentylacyjna zapewnia \u015bwie\u017ce i zdrowe powietrze w miejscach publicznych.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AL-KO EASYAIR\u00ae | AL-KO Air Technology\" \/>\n<meta property=\"og:description\" content=\"Nasza wydajna kompaktowa jednostka wentylacyjna zapewnia \u015bwie\u017ce i zdrowe powietrze w miejscach publicznych.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/\" \/>\n<meta property=\"og:site_name\" content=\"AL-KO Air Technology\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T12:43:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/\",\"url\":\"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/\",\"name\":\"AL-KO EASYAIR\u00ae | AL-KO Air Technology\",\"isPartOf\":{\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/#website\"},\"datePublished\":\"2022-03-02T09:10:55+00:00\",\"dateModified\":\"2025-05-14T12:43:09+00:00\",\"description\":\"Nasza wydajna kompaktowa jednostka wentylacyjna zapewnia \u015bwie\u017ce i zdrowe powietrze w miejscach publicznych.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/#website\",\"url\":\"https:\/\/alko-airtechnology.com\/pl\/\",\"name\":\"AL-KO Air Technology\",\"description\":\"Air Technology\",\"publisher\":{\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/alko-airtechnology.com\/pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/#organization\",\"name\":\"AL-KO Air Technology\",\"url\":\"https:\/\/alko-airtechnology.com\/pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/alko-airtechnology.com\/pl\/wp-content\/uploads\/sites\/9\/2021\/05\/AL-KO-Claim.svg\",\"contentUrl\":\"https:\/\/alko-airtechnology.com\/pl\/wp-content\/uploads\/sites\/9\/2021\/05\/AL-KO-Claim.svg\",\"width\":283,\"height\":114,\"caption\":\"AL-KO Air Technology\"},\"image\":{\"@id\":\"https:\/\/alko-airtechnology.com\/pl\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"AL-KO EASYAIR\u00ae | AL-KO Air Technology","description":"Nasza wydajna kompaktowa jednostka wentylacyjna zapewnia \u015bwie\u017ce i zdrowe powietrze w miejscach publicznych.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/","og_locale":"en_US","og_type":"article","og_title":"AL-KO EASYAIR\u00ae | AL-KO Air Technology","og_description":"Nasza wydajna kompaktowa jednostka wentylacyjna zapewnia \u015bwie\u017ce i zdrowe powietrze w miejscach publicznych.","og_url":"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/","og_site_name":"AL-KO Air Technology","article_modified_time":"2025-05-14T12:43:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/","url":"https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/","name":"AL-KO EASYAIR\u00ae | AL-KO Air Technology","isPartOf":{"@id":"https:\/\/alko-airtechnology.com\/pl\/#website"},"datePublished":"2022-03-02T09:10:55+00:00","dateModified":"2025-05-14T12:43:09+00:00","description":"Nasza wydajna kompaktowa jednostka wentylacyjna zapewnia \u015bwie\u017ce i zdrowe powietrze w miejscach publicznych.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alko-airtechnology.com\/pl\/product\/al-ko-easyair-your-central-ventilation-unit\/"]}]},{"@type":"WebSite","@id":"https:\/\/alko-airtechnology.com\/pl\/#website","url":"https:\/\/alko-airtechnology.com\/pl\/","name":"AL-KO Air Technology","description":"Air Technology","publisher":{"@id":"https:\/\/alko-airtechnology.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alko-airtechnology.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alko-airtechnology.com\/pl\/#organization","name":"AL-KO Air Technology","url":"https:\/\/alko-airtechnology.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alko-airtechnology.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/alko-airtechnology.com\/pl\/wp-content\/uploads\/sites\/9\/2021\/05\/AL-KO-Claim.svg","contentUrl":"https:\/\/alko-airtechnology.com\/pl\/wp-content\/uploads\/sites\/9\/2021\/05\/AL-KO-Claim.svg","width":283,"height":114,"caption":"AL-KO Air Technology"},"image":{"@id":"https:\/\/alko-airtechnology.com\/pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/alko-airtechnology.com\/pl\/wp-json\/wp\/v2\/wbq_product\/3247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alko-airtechnology.com\/pl\/wp-json\/wp\/v2\/wbq_product"}],"about":[{"href":"https:\/\/alko-airtechnology.com\/pl\/wp-json\/wp\/v2\/types\/wbq_product"}],"wp:attachment":[{"href":"https:\/\/alko-airtechnology.com\/pl\/wp-json\/wp\/v2\/media?parent=3247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}